{"id":23520,"date":"2025-03-27T09:43:34","date_gmt":"2025-03-27T09:43:34","guid":{"rendered":"https:\/\/f2dc07eea9a036484043cda0a7344ee6\/contactez-nous-2\/"},"modified":"2025-03-27T09:46:12","modified_gmt":"2025-03-27T09:46:12","slug":"contactez-nous-2","status":"publish","type":"page","link":"https:\/\/www.airain.com\/fr\/contactez-nous-2\/","title":{"rendered":"Contactez-nous"},"content":{"rendered":"\n  <div class=\"banner has-hover\" id=\"banner-1091258450\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill \"><\/div>\n                        <div class=\"overlay\"><\/div>            \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-1091258450 {\n  padding-top: 304px;\n}\n#banner-1091258450 .bg.bg-loaded {\n  background-image: url(https:\/\/www.airain.com\/wp-content\/uploads\/2020\/05\/airain-background2.jpg);\n}\n#banner-1091258450 .overlay {\n  background-color: rgba(0, 0, 0, 0.494);\n}\n#banner-1091258450 .bg {\n  background-position: 0% 69%;\n}\n@media (min-width:550px) {\n  #banner-1091258450 {\n    padding-top: 460px;\n  }\n}\n<\/style>\n  <\/div>\n\n\n\t<section class=\"section\" id=\"section_2073103488\">\n\t\t<div class=\"bg section-bg fill bg-fill  bg-loaded\" >\n\n\t\t\t\n\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<div class=\"row\"  id=\"row-1260538842\">\n\n\t<div id=\"col-2066238243\" class=\"col small-12 large-12\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div id=\"text-1667958500\" class=\"text\">\n\t\t\n<h3>NOTRE COMMUNAUT\u00c9 EST AUSSI IMPORTANTE QUE NOS MONTRES,<br \/>N&rsquo;H\u00c9SITEZ PAS \u00c0 NOUS CONTACTER POUR TOUTE QUESTION.<\/h3>\n\t\t\n<style>\n#text-1667958500 {\n  font-size: 2.5rem;\n  line-height: 1;\n  color: #323232;\n}\n#text-1667958500 > * {\n  color: #323232;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"is-divider divider clearfix\" style=\"max-width:100%;height:1px;\"><\/div>\n<p>Airain, brand of CDMLEC<br \/>Pastoor Vranckenlaan 34a<br \/>5953 CP Reuver<br \/>The Netherlands<br \/>KvK\/CoC: 73884138<br \/>VAT: NL859698257B01<\/p>\n\t<div id=\"gap-849292483\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-849292483 {\n  padding-top: 30px;\n}\n<\/style>\n\t<\/div>\n\t\n<div class=\"row\"  id=\"row-1555234524\">\n\n\t<div id=\"col-2121873242\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  <div class=\"banner has-hover\" id=\"banner-239891528\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill \"><\/div>\n                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-416848504\" class=\"text-box banner-layer x10 md-x10 lg-x10 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\t<div id=\"text-3472879928\" class=\"text\">\n\t\t\n<h3>APPELEZ-NOUS<\/h3>\n\t\t\n<style>\n#text-3472879928 {\n  font-size: 1rem;\n  line-height: 0.75;\n  text-align: left;\n  color: rgb(50, 50, 50);\n}\n#text-3472879928 > * {\n  color: rgb(50, 50, 50);\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-3691352627\" class=\"text\">\n\t\t\n<p>+31 20 800 5046<\/p>\n\t\t\n<style>\n#text-3691352627 {\n  font-size: 1rem;\n  line-height: 0.75;\n  text-align: left;\n  color: rgb(0,0,0);\n}\n#text-3691352627 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-416848504 {\n  width: 93%;\n}\n#text-box-416848504 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-239891528 {\n  padding-top: 200px;\n  background-color: rgb(225, 225, 225);\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1139854889\" class=\"col medium-4 small-12 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n  <div class=\"banner has-hover\" id=\"banner-892834250\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <div class=\"bg fill bg-fill \"><\/div>\n                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n   <div id=\"text-box-1848704508\" class=\"text-box banner-layer x50 md-x50 lg-x50 y50 md-y50 lg-y50 res-text\">\n                                <div class=\"text-box-content text dark\">\n              \n              <div class=\"text-inner text-center\">\n                  \n\t<div id=\"text-1481219960\" class=\"text\">\n\t\t\n<h3 data-opacity=\"0.7\">ENVOYEZ-NOUS UN MESSAGE<\/h3>\n\t\t\n<style>\n#text-1481219960 {\n  font-size: 1rem;\n  line-height: 0.75;\n  text-align: left;\n  color: #323232;\n}\n#text-1481219960 > * {\n  color: #323232;\n}\n<\/style>\n\t<\/div>\n\t\n\t<div id=\"text-1860974000\" class=\"text\">\n\t\t\n<p>I&#78;&#70;&#x4f;&#x40;&#x41;I&#82;&#65;&#x49;&#x4e;&#x2e;CO&#77;<\/p>\n\t\t\n<style>\n#text-1860974000 {\n  font-size: 1rem;\n  line-height: 0.75;\n  text-align: left;\n  color: rgb(0,0,0);\n}\n#text-1860974000 > * {\n  color: rgb(0,0,0);\n}\n<\/style>\n\t<\/div>\n\t\n              <\/div>\n           <\/div>\n                            \n<style>\n#text-box-1848704508 {\n  width: 81%;\n}\n#text-box-1848704508 .text-box-content {\n  font-size: 100%;\n}\n<\/style>\n    <\/div>\n \n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-892834250 {\n  padding-top: 200px;\n  background-color: rgb(225, 225, 225);\n}\n<\/style>\n  <\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_2073103488 {\n  padding-top: 142px;\n  padding-bottom: 142px;\n}\n<\/style>\n\t<\/section>\n\t\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-23520","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.airain.com\/fr\/wp-json\/wp\/v2\/pages\/23520","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.airain.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.airain.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.airain.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.airain.com\/fr\/wp-json\/wp\/v2\/comments?post=23520"}],"version-history":[{"count":0,"href":"https:\/\/www.airain.com\/fr\/wp-json\/wp\/v2\/pages\/23520\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.airain.com\/fr\/wp-json\/wp\/v2\/media?parent=23520"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}